1{"id":879,"count":2,"description":"","link":"https:\/\/liveporn.digital\/index.php\/actor\/atlanta-grey\/","name":"Atlanta Grey","slug":"atlanta-grey","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors\/879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/posts?actors=879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}