1{"id":5089,"count":1,"description":"","link":"https:\/\/liveporn.digital\/index.php\/actor\/dirk-jager\/","name":"Dirk Jager","slug":"dirk-jager","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors\/5089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/posts?actors=5089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}