1{"id":4885,"count":2,"description":"","link":"https:\/\/liveporn.digital\/index.php\/actor\/luke-milan\/","name":"Luke Milan","slug":"luke-milan","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors\/4885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/posts?actors=4885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}