1{"id":4129,"count":1,"description":"","link":"https:\/\/liveporn.digital\/index.php\/actor\/amone-bane\/","name":"Amone Bane","slug":"amone-bane","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors\/4129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/posts?actors=4129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}