1{"id":2907,"count":3,"description":"","link":"https:\/\/liveporn.digital\/index.php\/actor\/draven-navarro\/","name":"Draven Navarro","slug":"draven-navarro","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors\/2907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/liveporn.digital\/index.php\/wp-json\/wp\/v2\/posts?actors=2907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}